{"id":6232,"date":"2026-05-04T08:00:00","date_gmt":"2026-05-04T08:00:00","guid":{"rendered":"https:\/\/mairie-montataire.fr\/?post_type=event&#038;p=6232"},"modified":"2026-05-04T14:26:54","modified_gmt":"2026-05-04T14:26:54","slug":"woche-der-nachhaltigen-entwicklung","status":"publish","type":"event","link":"https:\/\/mairie-montataire.fr\/de\/agenda\/evenement\/semaine-du-developpement-durable\/","title":{"rendered":"Woche der nachhaltigen Entwicklung"},"content":{"rendered":"<p>Montataire setzt sich f\u00fcr unseren Planeten ein! Anl\u00e4sslich der Woche der nachhaltigen Entwicklung bietet die Stadt vom 2. bis 5. Juni 2026 ein reichhaltiges und abwechslungsreiches Programm f\u00fcr Schulen, die breite \u00d6ffentlichkeit und die Mitarbeiter der Stadtverwaltung an.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0);color:#00d084\" class=\"has-inline-color\">Highlights f\u00fcr alle - Donnerstag, 4. Juni, 16.30-18.30 Uhr auf der Esplanade Fernand Tuil<\/mark><\/strong><\/h3>\n\n\n\n<p>Die Kinder der EHH werden eine Ausstellung pr\u00e4sentieren, die sie selbst f\u00fcr diesen Anlass vorbereitet haben. Der Verein L'Agrion de l'Oise wird anwesend sein, um die \u00d6ffentlichkeit f\u00fcr das Leben der Insekten zu sensibilisieren, damit sie besser verstanden und gesch\u00fctzt werden k\u00f6nnen. Les Cr\u00e9as de vos envies wird eine Animation zum Thema Botanik und Blumenwelt durchf\u00fchren, an der sich Gro\u00df und Klein erfreuen k\u00f6nnen.<\/p>\n\n\n\n<p>M\u00f6chten Sie sofort anfangen? Dann machen Sie den ADEME-Selbsttest, um Ihren CO2-Fu\u00dfabdruck zu berechnen : <a href=\"https:\/\/bit.ly\/ADEME-EmpreinteCarbone?fbclid=IwZXh0bgNhZW0CMTAAYnJpZBEwVGZycVYwcUJ0aG42d2FaRQEefi3HIOP7uP-CQ7WOUijTuuk_T53irZFcEs82qgSRSViK4aeQ-7wxv2aZcB4_aem_cnlxhLBzUjkXf0b7FTCz3A\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/bit.ly\/ADEME-EmpreinteCarbone<\/a><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-3817c895\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-546bce6e wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/agirpourlatransition.ademe.fr\/particuliers\/conso\/conso-responsable\/connaissez-vous-votre-empreinte-climat\" rel=\"follow noopener\" target=\"_blank\" role=\"button\"><div class=\"uagb-button__link\">Wollen Sie sofort anfangen? <br>Dann machen Sie den ADEME-Selbsttest, um Ihren CO2-Fu\u00dfabdruck zu berechnen!<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0);color:#00d084\" class=\"has-inline-color\">Animationen f\u00fcr Sch\u00fcler<\/mark><\/strong><\/h3>\n\n\n\n<p>Am Dienstag, den 2. Juni, werden mehr als 800 Sch\u00fclerinnen und Sch\u00fcler an einem au\u00dfergew\u00f6hnlichen Tag im Park des Priorats teilnehmen, auf dessen Programm :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li style=\"font-style:normal;font-weight:400\">Sensibilisierung f\u00fcr Wassermanagement und Bioabfall mit der ACSO, <\/li>\n\n\n\n<li>Entdeckung von B\u00e4umen, Pflanzungen,<\/li>\n\n\n\n<li style=\"font-style:normal;font-weight:400\">Herstellung von Gegenst\u00e4nden aus recyceltem Kunststoff mit SAMJI, <\/li>\n\n\n\n<li style=\"font-style:normal;font-weight:400\">M\u00fcll sammeln, Spiele rund um die \u00d6ko-Mobilit\u00e4t und vieles mehr...<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0);color:#00d084\" class=\"has-inline-color\">Auch Gemeindebeamte engagieren sich<\/mark><\/strong><\/h3>\n\n\n\n<p>Am Freitag, dem 5. Juni, sind mehrere interne Aktionen geplant, um das Bewusstsein der st\u00e4dtischen Bediensteten zu sch\u00e4rfen :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li style=\"font-style:normal;font-weight:400\">Besuch des kommunalen Bienenhauses<\/li>\n\n\n\n<li>Vegetarisches Men\u00fc<\/li>\n\n\n\n<li style=\"font-style:normal;font-weight:400\">Digitale Herausforderungen ...<\/li>\n<\/ul>\n\n\n\n<p><\/p>","protected":false},"featured_media":6233,"parent":0,"template":"","meta":{"_acf_changed":true,"_uag_custom_page_level_css":""},"event-theme":[88],"class_list":["post-6232","event","type-event","status-publish","has-post-thumbnail","hentry","event-theme-evenement"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/mairie-montataire.fr\/app\/uploads\/2025\/05\/Agenda_SemaineDvldurable25.jpg",450,335,false],"thumbnail":["https:\/\/mairie-montataire.fr\/app\/uploads\/2025\/05\/Agenda_SemaineDvldurable25-150x150.jpg",150,150,true],"medium":["https:\/\/mairie-montataire.fr\/app\/uploads\/2025\/05\/Agenda_SemaineDvldurable25-300x223.jpg",300,223,true],"medium_large":["https:\/\/mairie-montataire.fr\/app\/uploads\/2025\/05\/Agenda_SemaineDvldurable25.jpg",450,335,false],"large":["https:\/\/mairie-montataire.fr\/app\/uploads\/2025\/05\/Agenda_SemaineDvldurable25.jpg",450,335,false],"1536x1536":["https:\/\/mairie-montataire.fr\/app\/uploads\/2025\/05\/Agenda_SemaineDvldurable25.jpg",450,335,false],"2048x2048":["https:\/\/mairie-montataire.fr\/app\/uploads\/2025\/05\/Agenda_SemaineDvldurable25.jpg",450,335,false],"trp-custom-language-flag":["https:\/\/mairie-montataire.fr\/app\/uploads\/2025\/05\/Agenda_SemaineDvldurable25-16x12.jpg",16,12,true],"gform-image-choice-sm":["https:\/\/mairie-montataire.fr\/app\/uploads\/2025\/05\/Agenda_SemaineDvldurable25.jpg",300,223,false],"gform-image-choice-md":["https:\/\/mairie-montataire.fr\/app\/uploads\/2025\/05\/Agenda_SemaineDvldurable25.jpg",400,298,false],"gform-image-choice-lg":["https:\/\/mairie-montataire.fr\/app\/uploads\/2025\/05\/Agenda_SemaineDvldurable25.jpg",450,335,false]},"uagb_author_info":{"display_name":"Laure Pubert","author_link":"https:\/\/mairie-montataire.fr\/de\/actualites\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Montataire s\u2019engage pour la plan\u00e8te ! \u00c0 l\u2019occasion de la Semaine du D\u00e9veloppement Durable, la Ville propose un programme riche et vari\u00e9, \u00e0 destination des scolaires, du grand public et des agents municipaux du 2 au 5 juin 2026. Temps forts tout public \u2013 Jeudi 4 juin de 16h30 \u00e0 18h30 \u00e0 l&rsquo;Esplanade Fernand Tuil&hellip;","_links":{"self":[{"href":"https:\/\/mairie-montataire.fr\/de\/wp-json\/wp\/v2\/event\/6232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mairie-montataire.fr\/de\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/mairie-montataire.fr\/de\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mairie-montataire.fr\/de\/wp-json\/wp\/v2\/media\/6233"}],"wp:attachment":[{"href":"https:\/\/mairie-montataire.fr\/de\/wp-json\/wp\/v2\/media?parent=6232"}],"wp:term":[{"taxonomy":"event-theme","embeddable":true,"href":"https:\/\/mairie-montataire.fr\/de\/wp-json\/wp\/v2\/event-theme?post=6232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}