{"id":8368,"date":"2026-09-02T10:10:47","date_gmt":"2026-09-02T10:10:47","guid":{"rendered":"https:\/\/mairie-montataire.fr\/?p=8368"},"modified":"2026-09-02T10:10:47","modified_gmt":"2026-09-02T10:10:47","slug":"avis-de-coupure-reseau-chaleur-jeudi-3-septembre","status":"publish","type":"post","link":"https:\/\/mairie-montataire.fr\/ar\/actualites\/avis-de-coupure-reseau-chaleur-jeudi-3-septembre\/","title":{"rendered":"Avis de coupure r\u00e9seau chaleur jeudi 3 septembre"},"content":{"rendered":"<p class=\"wp-block-paragraph\">L&rsquo;entreprise Dalkia et Oise Habitat nous informent :<br>Une fuite sur le r\u00e9seau de chaleur de Montataire impose des travaux de r\u00e9paration en urgence.<br><br>Nous serons dans l&rsquo;obligation de faire une coupure compl\u00e8te de la fourniture de chaleur pour le chauffage et l&rsquo;eau chaude sanitaire le jeudi 3 Septembre entre 8h00 et 18h00.<br><br>Les adresses impact\u00e9es sont les suivantes pour la fourniture du primaire pour chauffer l&rsquo;eau chaude sanitaire :<br>\u2022 1 rue du 19 mars 1962<br>\u2022 3 rue du 19 mars 1962<br>\u2022 13 rue du 19 mars 1962<br>\u2022 11 rue du 19 mars 1962<br>\u2022 9 rue du 19 mars 1962<br>\u2022 80, 82, 84, 86, 88 et 90 rue Maurice Thorez<br>\u2022 1 rue du Chemin Blanc<br>\u2022 1 et 3 rue Paul Vaillant Couturier<br>\u2022 28, 30, 32, 34 et 36 rue du Colonel Fabien<br>\u2022 1, 3, 5 et 7 Impasse de l&rsquo;Argili\u00e8re<br>\u2022 1, 3, 5 et 7 rue Jacques Decours<br>\u2022 2 et 4 rue Jacques Decours<br>\u2022 86, 88 et 90 avenue Anatole France<br>\u2022 82 et 84 avenue Anatole France<br>\u2022 76, 78 et 80 avenue Anatole France<br>\u2022 1 et 3 impasse des Martinets<br>\u2022 2 avenue Gabriel P\u00e9ri<br>\u2022 19, 21, 23, 25, 27 et 29 avenue Gabriel P\u00e9ri<br>\u2022 31, 33 et 35 avenue Gabriel P\u00e9ri<br>\u2022 37 et 39 avenue Gabriel P\u00e9ri<br>\u2022 SST 003MO &#8211; RES FOND CHEMIN BLANC &#8211; 5 rue du 19 mars 1962<br>\u2022 SST 012MO &#8211; COLLEGE A FRANCE<br>\u2022 SST 019MO &#8211; RES COLONEL FABIEN &#8211; 38 rue du Colonel Fabien<br>\u2022 SST 041MO &#8211; PISCINE DE MONTATAIRE<br>Veuillez nous excuser pour la g\u00eane occasionn\u00e9e.<\/p>","protected":false},"excerpt":{"rendered":"<p>L&rsquo;entreprise Dalkia et Oise Habitat nous informent :Une fuite sur le r\u00e9seau de chaleur de Montataire impose des travaux de r\u00e9paration en urgence. Nous serons dans l&rsquo;obligation de faire une coupure compl\u00e8te de la fourniture de chaleur pour le chauffage et l&rsquo;eau chaude sanitaire le jeudi 3 Septembre entre 8h00 et 18h00. Les adresses impact\u00e9es [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-8368","post","type-post","status-publish","format-standard","hentry","category-information"],"acf":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"S\u00e9verine Berger","author_link":"https:\/\/mairie-montataire.fr\/ar\/actualites\/author\/s-berger\/"},"uagb_comment_info":0,"uagb_excerpt":"L&rsquo;entreprise Dalkia et Oise Habitat nous informent :Une fuite sur le r\u00e9seau de chaleur de Montataire impose des travaux de r\u00e9paration en urgence. Nous serons dans l&rsquo;obligation de faire une coupure compl\u00e8te de la fourniture de chaleur pour le chauffage et l&rsquo;eau chaude sanitaire le jeudi 3 Septembre entre 8h00 et 18h00. Les adresses impact\u00e9es&hellip;","_links":{"self":[{"href":"https:\/\/mairie-montataire.fr\/ar\/wp-json\/wp\/v2\/posts\/8368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mairie-montataire.fr\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mairie-montataire.fr\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mairie-montataire.fr\/ar\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mairie-montataire.fr\/ar\/wp-json\/wp\/v2\/comments?post=8368"}],"version-history":[{"count":1,"href":"https:\/\/mairie-montataire.fr\/ar\/wp-json\/wp\/v2\/posts\/8368\/revisions"}],"predecessor-version":[{"id":8369,"href":"https:\/\/mairie-montataire.fr\/ar\/wp-json\/wp\/v2\/posts\/8368\/revisions\/8369"}],"wp:attachment":[{"href":"https:\/\/mairie-montataire.fr\/ar\/wp-json\/wp\/v2\/media?parent=8368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mairie-montataire.fr\/ar\/wp-json\/wp\/v2\/categories?post=8368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mairie-montataire.fr\/ar\/wp-json\/wp\/v2\/tags?post=8368"}],"curies":[{"name":"\u062f\u0628\u0644\u064a\u0648 \u0628\u064a","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}